{"id":3796,"date":"2021-09-14T07:06:50","date_gmt":"2021-09-14T07:06:50","guid":{"rendered":"https:\/\/embassyvallettahotel.kinsta.cloud\/?p=3796"},"modified":"2023-12-28T12:39:10","modified_gmt":"2023-12-28T12:39:10","slug":"pete-tongs-classics-live-from-malta","status":"publish","type":"post","link":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/","title":{"rendered":"Pete Tong&#8217;s Classics Live From Malta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3796\" class=\"elementor elementor-3796\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77995c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77995c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a8390c\" data-id=\"1a8390c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b11260 elementor-widget elementor-widget-text-editor\" data-id=\"6b11260\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>On the 28th September 2021, Revered DJ, broadcaster, and dance pioneer Pete Tong will be in Malta together with The Heritage Orchestra (HER_O) and conductor Jules Buckley, in a concert which will see some of the timeless classics making a well-deserved comeback.<\/p>\n<p>Pete Tong Classics promises to be an iconic classical electronic music event which is inventively bold and brightly reimagined.<\/p>\n<p>Three albums in with Classic House, Ibiza Classics and Chilled Classics, Tong and co are owning the dancefloor and the concert arena in a wholly fresh, forward-thinking way.<\/p>\n<p>The Malta Tourism Authority have also announced that, following recent updates to standing event protocols, Pete Tong Classics + The Heritage Orchestra will now be organised as a controlled STANDING event at The Granaries in Floriana &#8211; just a 10mins walk from our hotel!<\/p>\n<div class=\"jupiterx-main-content\" data-markup-id=\"jupiterx_main_content\">\n<div class=\"container-fluid\" data-markup-id=\"jupiterx_fixed_wrap[_main_content]\">\n<div class=\"row\" data-markup-id=\"jupiterx_main_grid\">\n<div id=\"jupiterx-primary\" class=\"jupiterx-primary col-lg-12\" data-markup-id=\"jupiterx_primary\">\n<div id=\"event-individual-event\" class=\"dtp-row\">\n<div class=\"dtp-se-container\">\n<div class=\"spost-section2\">\n<div class=\"dtp-column c75\">\n<div class=\"spost-addinfo-con\">\n<div class=\"spost-addinfo\">\n<p>The event will follow all the latest COVID-19 health and safety measures, and attendees will be grouped in bubbles of up to 100 with separate entrances, bars and amenities.<\/p>\n<p>Info provided by The Malta Tourism Authority.&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>On the 28th September 2021, Revered DJ, broadcaster, and dance pioneer Pete Tong will be in Malta together with The Heritage Orchestra (HER_O) and conductor Jules Buckley, in a concert which will see some of the timeless classics making a well-deserved comeback. Pete Tong Classics promises to be an iconic classical electronic music event which [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,18],"tags":[203,266,59,282,35,81,36,129,204,245,66,267],"month":[],"class_list":["post-3796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-past-events","tag-dailyevents","tag-gozo","tag-musicmalta","tag-petetong","tag-valletta","tag-vallettaevents","tag-vallettaexperience","tag-vallettatheatre","tag-vallettaviews","tag-visitmalta","tag-whatsonmalta","tag-whatsonvalletta-gozoferry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pete Tong&#039;s Classics Live From Malta - The Embassy Valletta Hotel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pete Tong&#039;s Classics Live From Malta - The Embassy Valletta Hotel\" \/>\n<meta property=\"og:description\" content=\"On the 28th September 2021, Revered DJ, broadcaster, and dance pioneer Pete Tong will be in Malta together with The Heritage Orchestra (HER_O) and conductor Jules Buckley, in a concert which will see some of the timeless classics making a well-deserved comeback. Pete Tong Classics promises to be an iconic classical electronic music event which [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/\" \/>\n<meta property=\"og:site_name\" content=\"The Embassy Valletta Hotel\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-14T07:06:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T12:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chris Borg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chris Borg\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/\"},\"author\":{\"name\":\"Chris Borg\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#\\\/schema\\\/person\\\/a80a5f65178da49ddd6ed1782646a5dd\"},\"headline\":\"Pete Tong&#8217;s Classics Live From Malta\",\"datePublished\":\"2021-09-14T07:06:50+00:00\",\"dateModified\":\"2023-12-28T12:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/\"},\"wordCount\":175,\"publisher\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PeteTong.jpg\",\"keywords\":[\"#dailyevents\",\"#gozo\",\"#musicmalta\",\"#petetong\",\"#valletta\",\"#vallettaevents\",\"#vallettaexperience\",\"#vallettatheatre\",\"#vallettaviews\",\"#visitmalta\",\"#whatsonmalta\",\"#whatsonvalletta #gozoferry\"],\"articleSection\":[\"Events\",\"Past Events\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/\",\"name\":\"Pete Tong's Classics Live From Malta - The Embassy Valletta Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PeteTong.jpg\",\"datePublished\":\"2021-09-14T07:06:50+00:00\",\"dateModified\":\"2023-12-28T12:39:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PeteTong.jpg\",\"contentUrl\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/PeteTong.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/pete-tongs-classics-live-from-malta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pete Tong&#8217;s Classics Live From Malta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/\",\"name\":\"The Embassy Valletta Hotel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#organization\",\"name\":\"The Embassy Valletta Hotel\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Embassy-Valletta-Hotel-Logo-G.png\",\"contentUrl\":\"https:\\\/\\\/embassyvallettahotel.com\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/Embassy-Valletta-Hotel-Logo-G.png\",\"width\":801,\"height\":146,\"caption\":\"The Embassy Valletta Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/#\\\/schema\\\/person\\\/a80a5f65178da49ddd6ed1782646a5dd\",\"name\":\"Chris Borg\",\"url\":\"https:\\\/\\\/embassyvallettahotel.com\\\/fr\\\/blog\\\/author\\\/chrisb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pete Tong's Classics Live From Malta - The Embassy Valletta Hotel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/","og_locale":"fr_FR","og_type":"article","og_title":"Pete Tong's Classics Live From Malta - The Embassy Valletta Hotel","og_description":"On the 28th September 2021, Revered DJ, broadcaster, and dance pioneer Pete Tong will be in Malta together with The Heritage Orchestra (HER_O) and conductor Jules Buckley, in a concert which will see some of the timeless classics making a well-deserved comeback. Pete Tong Classics promises to be an iconic classical electronic music event which [&hellip;]","og_url":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/","og_site_name":"The Embassy Valletta Hotel","article_published_time":"2021-09-14T07:06:50+00:00","article_modified_time":"2023-12-28T12:39:10+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg","type":"image\/jpeg"}],"author":"Chris Borg","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris Borg","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#article","isPartOf":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/"},"author":{"name":"Chris Borg","@id":"https:\/\/embassyvallettahotel.com\/fr\/#\/schema\/person\/a80a5f65178da49ddd6ed1782646a5dd"},"headline":"Pete Tong&#8217;s Classics Live From Malta","datePublished":"2021-09-14T07:06:50+00:00","dateModified":"2023-12-28T12:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/"},"wordCount":175,"publisher":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/#organization"},"image":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#primaryimage"},"thumbnailUrl":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg","keywords":["#dailyevents","#gozo","#musicmalta","#petetong","#valletta","#vallettaevents","#vallettaexperience","#vallettatheatre","#vallettaviews","#visitmalta","#whatsonmalta","#whatsonvalletta #gozoferry"],"articleSection":["Events","Past Events"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/","url":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/","name":"Pete Tong's Classics Live From Malta - The Embassy Valletta Hotel","isPartOf":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#primaryimage"},"image":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#primaryimage"},"thumbnailUrl":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg","datePublished":"2021-09-14T07:06:50+00:00","dateModified":"2023-12-28T12:39:10+00:00","breadcrumb":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#primaryimage","url":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg","contentUrl":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2021\/09\/PeteTong.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/embassyvallettahotel.com\/fr\/blog\/pete-tongs-classics-live-from-malta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/embassyvallettahotel.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Pete Tong&#8217;s Classics Live From Malta"}]},{"@type":"WebSite","@id":"https:\/\/embassyvallettahotel.com\/fr\/#website","url":"https:\/\/embassyvallettahotel.com\/fr\/","name":"The Embassy Valletta Hotel","description":"","publisher":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/embassyvallettahotel.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/embassyvallettahotel.com\/fr\/#organization","name":"The Embassy Valletta Hotel","url":"https:\/\/embassyvallettahotel.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/embassyvallettahotel.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2019\/01\/Embassy-Valletta-Hotel-Logo-G.png","contentUrl":"https:\/\/embassyvallettahotel.com\/wp-content\/uploads\/2019\/01\/Embassy-Valletta-Hotel-Logo-G.png","width":801,"height":146,"caption":"The Embassy Valletta Hotel"},"image":{"@id":"https:\/\/embassyvallettahotel.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/embassyvallettahotel.com\/fr\/#\/schema\/person\/a80a5f65178da49ddd6ed1782646a5dd","name":"Chris Borg","url":"https:\/\/embassyvallettahotel.com\/fr\/blog\/author\/chrisb\/"}]}},"_links":{"self":[{"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/posts\/3796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/comments?post=3796"}],"version-history":[{"count":3,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/posts\/3796\/revisions"}],"predecessor-version":[{"id":8740,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/posts\/3796\/revisions\/8740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/media\/3798"}],"wp:attachment":[{"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/media?parent=3796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/categories?post=3796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/tags?post=3796"},{"taxonomy":"month","embeddable":true,"href":"https:\/\/embassyvallettahotel.com\/fr\/wp-json\/wp\/v2\/month?post=3796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}